{"id":1527,"date":"2018-05-05T12:45:06","date_gmt":"2018-05-05T10:45:06","guid":{"rendered":"https:\/\/2018.bari.wordcamp.org\/?p=1527"},"modified":"2018-05-05T12:45:06","modified_gmt":"2018-05-05T10:45:06","slug":"tour-della-citta","status":"publish","type":"post","link":"https:\/\/bari.wordcamp.org\/2018\/tour-della-citta\/","title":{"rendered":"Tour della citt\u00e0 &#8211; Non solo codice!"},"content":{"rendered":"<p>Hai voglia di un after-after party prima di tornare a casa?<br \/>\nDomenica 13 maggio regalati un tour all&#8217;interno della citt\u00e0 vecchia!<br \/>\nDalle 9:30, potrai trascorrere tre ore in giro tra le bellezze di Bari Vecchia, percorrendo duemila anni, cinquemila chilometri, quattro religioni.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1528 size-full\" src=\"https:\/\/2018.bari.wordcamp.org\/files\/2018\/05\/visitaturisticabari.png\" alt=\"\" width=\"648\" height=\"434\" srcset=\"https:\/\/bari.wordcamp.org\/2018\/files\/2018\/05\/visitaturisticabari.png 648w, https:\/\/bari.wordcamp.org\/2018\/files\/2018\/05\/visitaturisticabari-300x201.png 300w, https:\/\/bari.wordcamp.org\/2018\/files\/2018\/05\/visitaturisticabari-448x300.png 448w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/p>\n<p>Tre percorsi raccontati con passione e dedizione da Nicola Dellino.<br \/>\nCercheremo di raccontarvi il perch\u00e9, passeggiando per Bari vecchia, si diventa inspiegabilmente felici.<\/p>\n<p><strong>1\u00b0 ITINERARIO<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1535 size-full\" src=\"https:\/\/2018.bari.wordcamp.org\/files\/2018\/05\/itinerario1.png\" alt=\"\" width=\"584\" height=\"790\" srcset=\"https:\/\/bari.wordcamp.org\/2018\/files\/2018\/05\/itinerario1.png 584w, https:\/\/bari.wordcamp.org\/2018\/files\/2018\/05\/itinerario1-222x300.png 222w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/p>\n<p>A) PIAZZA DEL FERRARESE<br \/>\n1. Sala Murat<br \/>\n2. Mercato coperto<br \/>\n3. Pavimentazione sottostante la \u201cporta di mare\u201d<br \/>\n4. La Vallisa<br \/>\n5. La salita per Via Venezia<br \/>\n6. Palazzo Starita<\/p>\n<p>B) PIAZZA DEL MERCANTILE<br \/>\n1. Il palazzo del Sedile<br \/>\n2. La Colonna della Giustizia<br \/>\n3. Via Manfredi<br \/>\n4. La Cappella Sant\u2019Antonio Abate<br \/>\n5. Fontana della Pigna<br \/>\n6. Vicolo Fiscardi<br \/>\n7. Il palazzo della Dogana<\/p>\n<p>C) STRADA PALAZZO DI CITTA\u2019<br \/>\n1. Chiesa di Sant\u2019Anna<br \/>\n2. Palazzo Cognetti<br \/>\n3. Palazzo D\u2019Ameli<br \/>\n4. Palazzo Tanzi<br \/>\n5. Collegio dei Gesuiti<br \/>\n6. Palazzo Zizzi<br \/>\n7. Panificio Fiore (resti di antica chiesa)<br \/>\n8. Palazzo Casamassimi<br \/>\n9. Arco S. Nicola<br \/>\n10. San Nicola e San Gregorio Magno<\/p>\n<p><strong>2\u00b0 ITINERARIO<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1536 size-full\" src=\"https:\/\/2018.bari.wordcamp.org\/files\/2018\/05\/itinerario2.png\" alt=\"\" width=\"568\" height=\"684\" srcset=\"https:\/\/bari.wordcamp.org\/2018\/files\/2018\/05\/itinerario2.png 568w, https:\/\/bari.wordcamp.org\/2018\/files\/2018\/05\/itinerario2-249x300.png 249w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p>D) SALITA PER LA MURAGLIA<br \/>\n1. Fortino di Sant\u2019Antonio (DX)<br \/>\n2. Colonne Romane (sotto)<br \/>\n3. Palazzi in vario stile architettonico (SX)<br \/>\n4. Monastero di Santa Scolastica<\/p>\n<p>E) PIAZZA SAN PIETRO<br \/>\nF) SANTA MARIA DEL POPOLO (O DEL BUONCONSIGLIO)<br \/>\nG) STRADA QUERCIA (LA CAPE DU TURCHIE)<br \/>\nH) CHIESA DI SANTA CHIARA<br \/>\nI) CHIESA DI SAN GIOVANNI CRISOSTOMO<br \/>\nL) CHIESA DI SANTA MARIA DEL CARMINE<br \/>\nM) CHIESETTA DI SAN MARCO<br \/>\nN) CASA DEL CONSOLE VENEZIANO<br \/>\nO) CATTEDRALE DI SAN SABINO<br \/>\n1. Duomo<br \/>\n2. Piazzetta Bisanzio e Raialdo<br \/>\n3. Cisterna di Bona Sforza<br \/>\n4. Arcivescovado<br \/>\n5. Palazzo EFREM\/DE ANGELIS<\/p>\n<p>P) CHIESA DI SAN GAETANO<br \/>\nQ) ARCO MERAVIGLIA<\/p>\n<p><strong>3\u00b0 ITINERARIO<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1537 size-full\" src=\"https:\/\/2018.bari.wordcamp.org\/files\/2018\/05\/itinerario3.png\" alt=\"\" width=\"570\" height=\"717\" srcset=\"https:\/\/bari.wordcamp.org\/2018\/files\/2018\/05\/itinerario3.png 570w, https:\/\/bari.wordcamp.org\/2018\/files\/2018\/05\/itinerario3-238x300.png 238w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/p>\n<p>A) DA PIAZZA ODEGITRIA<br \/>\n1. Chiesa di San Giacomo<br \/>\n2. Chiesa SS. Trinit\u00e0 e SS. Medici<\/p>\n<p>B) PIAZZA FEDERICO II DI SVEVIA<br \/>\n1. Castello<br \/>\n2. Arco Basso<br \/>\n3. Arco Alto &#8211; San Sebastiano<\/p>\n<p>C) SAN DOMENICO<br \/>\nD) PALAZZO DIANA &#8211; Resti cappella di San Bartolomeo<br \/>\nE) MONASTERO DI SAN BENEDETTO, CHIESA DI SAN MICHELE<br \/>\nF) PALAZZO GIRONDA<br \/>\nG) CHIESA DI SANTA TERESA DEI MASCHI<br \/>\nRitorno a Piazza Del Ferrarese.<\/p>\n<p>Il percorso turistico <strong>ha un costo di 5\u20ac<\/strong>\u00a0a persona da versare direttamente alla guida al momento dell&#8217;incontro.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hai voglia di un after-after party prima di tornare a casa? Domenica 13 maggio regalati un tour all&#8217;interno della citt\u00e0 vecchia! Dalle 9:30, potrai trascorrere tre ore in giro tra le bellezze di Bari Vecchia, percorrendo duemila anni, cinquemila chilometri, quattro religioni. Tre percorsi raccontati con passione e dedizione da Nicola Dellino. Cercheremo di raccontarvi &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/bari.wordcamp.org\/2018\/tour-della-citta\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Tour della citt\u00e0 &#8211; Non solo codice!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":15551800,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-1527","post","type-post","status-publish","format-standard","hentry","category-news"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMry-oD","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15551800"}],"replies":[{"embeddable":true,"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=1527"}],"version-history":[{"count":4,"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1527\/revisions"}],"predecessor-version":[{"id":1541,"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1527\/revisions\/1541"}],"wp:attachment":[{"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=1527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bari.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=1527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}