{"id":1025,"date":"2019-04-24T12:32:17","date_gmt":"2019-04-24T10:32:17","guid":{"rendered":"https:\/\/2019.bari.wordcamp.org\/?post_type=wcb_session&#038;p=1025"},"modified":"2019-05-04T11:52:43","modified_gmt":"2019-05-04T09:52:43","slug":"insegnare-wordpress-da-zero","status":"publish","type":"wcb_session","link":"https:\/\/bari.wordcamp.org\/2019\/session\/insegnare-wordpress-da-zero\/","title":{"rendered":"Insegnare WordPress da zero"},"content":{"rendered":"<p>Con l&#8217;aiuto di slide e fumetti, vorrei illustrarvi un metodo consolidato di insegnare il funzionamento di WordPress anche a chi inizia un percorso da zero, senza avere nessuna conoscenza di linguaggio di codice. Vedremo come dividere in diverse fasi l&#8217;apprendimento, partendo dall&#8217;utilizzo di WordPress con i suoi strumenti base, passando poi al codice di marcatura Html e Css, quindi al PHP e JavaScript fino alla realizzazione di un tema da zero. Una didattica pratica, circolare e condivisa, basata sull&#8217;esercizio e la creativit\u00e0, per diventare sviluppatori di WordPress con consapevolezza e senza annoiarsi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con l&#8217;aiuto di slide e fumetti, vorrei illustrarvi un metodo consolidato di insegnare il funzionamento di WordPress anche a chi inizia un percorso da zero, senza avere nessuna conoscenza di linguaggio di codice. Vedremo come dividere in diverse fasi l&#8217;apprendimento, partendo dall&#8217;utilizzo di WordPress con i suoi strumenti base, passando poi al codice di marcatura [&hellip;]<\/p>\n","protected":false},"author":14789641,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1558182600,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"https:\/\/docs.google.com\/presentation\/d\/1wdcRpg8YsVZu7Gy-CySbINq_E7nQP7czymGlnlUCqek\/edit?usp=sharing","_wcpt_session_video":"","_wcpt_speaker_id":[986],"footnotes":""},"session_track":[1282758],"session_category":[],"class_list":["post-1025","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-area-g-scott-heron"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheHte-gx","session_date_time":{"date":"18 Maggio 2019","time":"14:30"},"session_speakers":[{"id":"986","slug":"francesco-riggio","name":"Francesco Riggio","link":"https:\/\/bari.wordcamp.org\/2019\/speaker\/francesco-riggio\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/1025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":2,"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/1025\/revisions"}],"predecessor-version":[{"id":1172,"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/1025\/revisions\/1172"}],"speakers":[{"embeddable":true,"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wp\/v2\/speakers\/986"}],"author":[{"embeddable":true,"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wporg\/v1\/users\/fra_riggio"}],"wp:attachment":[{"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=1025"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_track?post=1025"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/bari.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_category?post=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}